{
    "id": 2712,
    "count": 1,
    "description": "",
    "link": "https:\/\/auctionautosale.mn\/en_us\/category\/concorsorestorations-co-uk-10\/",
    "name": "concorsorestorations.co.uk-10",
    "slug": "concorsorestorations-co-uk-10",
    "taxonomy": "category",
    "parent": 0,
    "meta": [],
    "_links": {
        "self": [
            {
                "href": "https:\/\/auctionautosale.mn\/en_us\/wp-json\/wp\/v2\/categories\/2712",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/auctionautosale.mn\/en_us\/wp-json\/wp\/v2\/categories"
            }
        ],
        "about": [
            {
                "href": "https:\/\/auctionautosale.mn\/en_us\/wp-json\/wp\/v2\/taxonomies\/category"
            }
        ],
        "wp:post_type": [
            {
                "href": "https:\/\/auctionautosale.mn\/en_us\/wp-json\/wp\/v2\/posts?categories=2712"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}